{"id":134,"count":87,"description":"D\u00e9couvrez les meilleures choses \u00e0 faire \u00e0 Antalya avec notre vaste s\u00e9lection d'excursions et d'activit\u00e9s inoubliables \u00e0 Antalya. Naviguez sur les eaux turquoise lors d'une excursion en yacht ou en bateau priv\u00e9, ou offrez-vous un yacht de luxe pour une exp\u00e9rience plus exclusive. Les plus aventureux peuvent faire un safari en quad, en buggy ou en jeep ou faire une passionnante excursion en rafting \u00e0 travers les montagnes du Taurus. Plongez dans la riche culture d'Antalya avec des excursions guid\u00e9es vers des sites antiques tels que Perg\u00e9, Aspendos et Side. D\u00e9couvrez la beaut\u00e9 de la nature en visitant les cascades \u00e0 couper le souffle de D\u00fcden ou profitez d'une excursion d'une journ\u00e9e compl\u00e8te sur les terrasses de travertin blanc de Pamukkale. Pour une aventure inoubliable, rejoignez notre excursion de 2 jours en Cappadoce et flottez au-dessus des chemin\u00e9es de f\u00e9es en montgolfi\u00e8re. Que vous recherchiez des activit\u00e9s de d\u00e9tente, de culture ou d'adr\u00e9naline, nos excursions \u00e0 Antalya promettent quelque chose pour tout le monde. R\u00e9servez votre voyage de r\u00eave \u00e0 Antalya d\u00e8s aujourd'hui\u00a0! 1071 VUDAA TRAVEL est toujours heureux de vous servir sous le soleil d'Antalya.","link":"https:\/\/www.dailycitytoursantalya.com\/fr\/ba_location\/antalya\/","name":"Excursions et activit\u00e9s \u00e0 Antalya","slug":"antalya","taxonomy":"ba_location","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Excursions et activit\u00e9s \u00e0 Antalya Archives - Excursions \u00e0 Antalya<\/title>\n<meta name=\"description\" content=\"Les excursions et les activit\u00e9s \u00e0 Antalya conqui\u00e8rent sans effort le c\u0153ur de tous. 1071 VUDAA TRAVEL est toujours heureux de vous servir \u00e0 Antalya.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dailycitytoursantalya.com\/fr\/ba_location\/antalya\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Excursions et activit\u00e9s \u00e0 Antalya Archives - Excursions \u00e0 Antalya\" \/>\n<meta property=\"og:description\" content=\"Les excursions et les activit\u00e9s \u00e0 Antalya conqui\u00e8rent sans effort le c\u0153ur de tous. 1071 VUDAA TRAVEL est toujours heureux de vous servir \u00e0 Antalya.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dailycitytoursantalya.com\/fr\/ba_location\/antalya\/\" \/>\n<meta property=\"og:site_name\" content=\"Excursions \u00e0 Antalya\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.dailycitytoursantalya.com\/fr\/ba_location\/antalya\/\",\"url\":\"https:\/\/www.dailycitytoursantalya.com\/fr\/ba_location\/antalya\/\",\"name\":\"Excursions et activit\u00e9s \u00e0 Antalya Archives - Excursions \u00e0 Antalya\",\"isPartOf\":{\"@id\":\"https:\/\/www.dailycitytoursantalya.com\/fr\/#website\"},\"description\":\"Les excursions et les activit\u00e9s \u00e0 Antalya conqui\u00e8rent sans effort le c\u0153ur de tous. 1071 VUDAA TRAVEL est toujours heureux de vous servir \u00e0 Antalya.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.dailycitytoursantalya.com\/fr\/ba_location\/antalya\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.dailycitytoursantalya.com\/fr\/ba_location\/antalya\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.dailycitytoursantalya.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Excursions et activit\u00e9s \u00e0 Antalya\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.dailycitytoursantalya.com\/fr\/#website\",\"url\":\"https:\/\/www.dailycitytoursantalya.com\/fr\/\",\"name\":\"Excursions \u00e0 Antalya\",\"description\":\"Excursions d&#039;une journ\u00e9e \u00e0 Antalya\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.dailycitytoursantalya.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Excursions et activit\u00e9s \u00e0 Antalya Archives - Excursions \u00e0 Antalya","description":"Les excursions et les activit\u00e9s \u00e0 Antalya conqui\u00e8rent sans effort le c\u0153ur de tous. 1071 VUDAA TRAVEL est toujours heureux de vous servir \u00e0 Antalya.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dailycitytoursantalya.com\/fr\/ba_location\/antalya\/","og_locale":"en_GB","og_type":"article","og_title":"Excursions et activit\u00e9s \u00e0 Antalya Archives - Excursions \u00e0 Antalya","og_description":"Les excursions et les activit\u00e9s \u00e0 Antalya conqui\u00e8rent sans effort le c\u0153ur de tous. 1071 VUDAA TRAVEL est toujours heureux de vous servir \u00e0 Antalya.","og_url":"https:\/\/www.dailycitytoursantalya.com\/fr\/ba_location\/antalya\/","og_site_name":"Excursions \u00e0 Antalya","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.dailycitytoursantalya.com\/fr\/ba_location\/antalya\/","url":"https:\/\/www.dailycitytoursantalya.com\/fr\/ba_location\/antalya\/","name":"Excursions et activit\u00e9s \u00e0 Antalya Archives - Excursions \u00e0 Antalya","isPartOf":{"@id":"https:\/\/www.dailycitytoursantalya.com\/fr\/#website"},"description":"Les excursions et les activit\u00e9s \u00e0 Antalya conqui\u00e8rent sans effort le c\u0153ur de tous. 1071 VUDAA TRAVEL est toujours heureux de vous servir \u00e0 Antalya.","breadcrumb":{"@id":"https:\/\/www.dailycitytoursantalya.com\/fr\/ba_location\/antalya\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/www.dailycitytoursantalya.com\/fr\/ba_location\/antalya\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.dailycitytoursantalya.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Excursions et activit\u00e9s \u00e0 Antalya"}]},{"@type":"WebSite","@id":"https:\/\/www.dailycitytoursantalya.com\/fr\/#website","url":"https:\/\/www.dailycitytoursantalya.com\/fr\/","name":"Excursions \u00e0 Antalya","description":"Excursions d&#039;une journ\u00e9e \u00e0 Antalya","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dailycitytoursantalya.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/www.dailycitytoursantalya.com\/fr\/wp-json\/wp\/v2\/ba_location\/134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dailycitytoursantalya.com\/fr\/wp-json\/wp\/v2\/ba_location"}],"about":[{"href":"https:\/\/www.dailycitytoursantalya.com\/fr\/wp-json\/wp\/v2\/taxonomies\/ba_location"}]}}